{"id":15428,"date":"2016-10-01T00:00:00","date_gmt":"2016-09-30T22:00:00","guid":{"rendered":"http:\/\/test.graswurzel.net\/gwr\/2016\/10\/ne-znam-3\/"},"modified":"2022-07-26T14:11:54","modified_gmt":"2022-07-26T12:11:54","slug":"ne-znam-3","status":"publish","type":"post","link":"https:\/\/www.graswurzel.net\/gwr\/2016\/10\/ne-znam-3\/","title":{"rendered":"Ne znam! #3"},"content":{"rendered":"<p>Das Erscheinen der dritten Ausgabe von &#8222;Ne znam. Zeitschrift f\u00fcr Anarchismusforschung&#8220; beweist, dass es sowohl Bedarf an einer solchen Zeitschrift in Deutschland gibt als auch dass der Herausgeber Philippe Kellermann die Ausdauer besitzt, dies umzusetzen. Nach wie vor wird die Zeitschrift nur von ihm herausgegeben und nicht von einem Kollektiv, wie es sich f\u00fcr ein solches Projekt anbieten w\u00fcrde. Bez\u00fcglich der Beitr\u00e4ger l\u00e4sst sich ebenfalls eine Kontinuit\u00e4t erkennen &#8211; Andreas L\u00f6hrer, Andreas F\u00f6rster, Wolfgang Eckhardt, Findus und Wolfgang Reinhard, die auch an den letzten Ausgaben mitgearbeitet haben. Sein eigenes Vorwort f\u00e4llt wie in den vergangenen Ausgaben etwas lapidar aus. &#8222;Wer sich jedenfalls fragt, was die &#8222;Ne znam&#8220; eigentlich soll &#8211; und mit ihr bezweckt wird, dem sei gesagt: Garnichts!&#8220; (S. 1).<\/p>\n<p>Im Gegensatz zu den vorherigen Ausgaben l\u00e4sst sich bei dieser Ausgabe ein Schwerpunkt im Bereich der Auseinandersetzung mit dem spanischen Anarchismus bzw. dem sehr eng geschichtlich mit ihm verkn\u00fcpften Anarchosyndikalismus erkennen. So besch\u00e4ftigen sich die Beitr\u00e4ge von Walther L. Bernecker (&#8222;Anarchistische Gewaltformen im Spanien des 19. Jahrhunderts&#8220;) und von Lily Litvak (&#8222;Die Kultur des spanischen Anarchismus&#8220;) mit erstgenannten Thema w\u00e4hrend Hartmut R\u00fcbners Text &#8222;Solidargemeinschaften in gef\u00e4hrlichen Zeiten&#8220; sowie das historische Dokument, ein Text von Victor &#8222;Le R\u00e9tif&#8220; Serge (&#8222;Unser Antisyndikalismus&#8220;) sich in letzteres einordnen lassen.<\/p>\n<p>Drei weitere Beitr\u00e4ge besch\u00e4ftigen sich mit dem internationalen Kampf gegen anarchistischen Terrorismus zwischen 1878-1934 (Richard Bach Jensen), Anarchismus Wagners (Olaf Briese) sowie mit dem Verh\u00e4ltnis von Posthumanismus und Anarchismus (Simon Schaupp). Abgerundet wird die Ausgabe mit f\u00fcnf Rezensionen &#8211; u.a. von englisch- und franz\u00f6sischsprachigen Ver\u00f6ffentlichungen. (Hierbei muss sich der Herausgeber die Frage stellen, ob es Sinn macht, fremdsprachige B\u00fccher zu rezensieren, die in Deutschland nicht oder nur sehr schwer zug\u00e4nglich sind.) Unter den besprochenen B\u00fcchern findet sich auch eine Rezension zu einem vom Philippe Kellermann herausgegebenen Band.<\/p>\n<p>Auff\u00e4llig ist auch in dieser Ausgabe, dass etwa die H\u00e4lfte der Beitr\u00e4ge bereits publiziert wurden, im Netz freizug\u00e4nglich sind und lediglich &#8211; wenn auch in deutscher \u00dcbersetzung &#8211; hier nachgedruckt wurden. Dies betrifft die Beitr\u00e4ge von Richard Bach Jensen, Lily Litvak, die Anmerkungen zum historischen Dokument sowie eine Rezension. Der Text von Hartmut R\u00fcbner ist ebenfalls nur eine gek\u00fcrzte Fassung eines, gemeinsam mit Dieter Nelles verfassten Beitrages f\u00fcr das Journal &#8222;Moving the Social&#8220;. F\u00fcr eine Zeitschrift f\u00fcr Anarchismusforschung w\u00fcrde ich mir pers\u00f6nlich mehr exklusive Beitr\u00e4ge w\u00fcnschen. Das Potential sehe ich pers\u00f6nlich in der deutschsprachigen A-Landschaft auch gegeben.<\/p>\n<p>Bez\u00fcglich der Qualit\u00e4t der Beitr\u00e4ge kann man nat\u00fcrlich nicht meckern &#8211; Autor*innen wie Walther L. Bernecker, Lily Litvak oder Hartmut R\u00fcbner sind wissenschaftliche Koryph\u00e4en in ihrem jeweiligen Bereich. Der Beitrag von Olaf Briese weist dagegen in Bezug auf die Proudhonrezeption Wagners einige blinde Flecken auf und verbleibt damit leider partiell hinter dem aktuellem Forschungsstand zu Wagner zur\u00fcck.<\/p>\n<p>Der Eindruck der Ausgabe ist durchwachsen. Ich denke, dass die Zeitschrift ihrem Anspruch, den sie entgegen den Vorworten von Philippe Kellermann mit ihrem Untertitel &#8222;Zeitschrift f\u00fcr Anarchismusforschung&#8220; zum Ausdruck bringt &#8211; nach wie vor nur bedingt erf\u00fcllt. Manchmal hatte ich bei der Lekt\u00fcre den Eindruck, dass die Zeitschrift weder Fisch noch Fleisch ist. Es w\u00fcrde sich anbieten, ein Periodikum mit eigenen Exklusivbeitr\u00e4gen zu publizieren oder lediglich \u00dcbersetzungen zu bringen. Die vorliegende Mischung durchkreuzt beides, aber nicht in Bezug auf eine sinnvolle Symbiose beider Konzepte. Die Themenwahl ist bunt durchmischt und der bekannte rote Faden l\u00e4sst sich nur schwer erkennen.<\/p>\n<p>Die Beitr\u00e4ge sind von Interesse, aber wenn ich sie bei Bedarf zum gro\u00dfen Teil in der Originalfassung ohnehin im Internet finde, ben\u00f6tige ich nicht unbedingt eine Publikation wie &#8222;Ne znam!&#8220;.<\/p>\n<p>Die Zeitschrift hat sicherlich Potentiale, aber diese werden nicht ausgesch\u00f6pft. Sie k\u00f6nnen bei einem halbj\u00e4hrlichen Erscheinungsturnus von einem Einzelherausgeber auch gar nicht ad\u00e4quat umgesetzt werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Erscheinen der dritten Ausgabe von &#8222;Ne znam. Zeitschrift f\u00fcr Anarchismusforschung&#8220; beweist, dass es sowohl Bedarf an einer solchen Zeitschrift in Deutschland gibt als auch dass der Herausgeber Philippe Kellermann die Ausdauer besitzt, dies umzusetzen. Nach wie vor wird die Zeitschrift nur von ihm herausgegeben und nicht von einem Kollektiv, wie es sich f\u00fcr ein &hellip; <a href=\"https:\/\/www.graswurzel.net\/gwr\/2016\/10\/ne-znam-3\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"slim_seo":{"title":"Ne znam! #3 - graswurzelrevolution","description":"Das Erscheinen der dritten Ausgabe von \"Ne znam. Zeitschrift f\u00fcr Anarchismusforschung\" beweist, dass es sowohl Bedarf an einer solchen Zeitschrift in Deutschlan"},"footnotes":""},"categories":[900,44,1042],"tags":[],"class_list":["post-15428","post","type-post","status-publish","format-standard","hentry","category-412-oktober-2016","category-bucher","category-ohne-chef-und-staat"],"_links":{"self":[{"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/posts\/15428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/comments?post=15428"}],"version-history":[{"count":0,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/posts\/15428\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/media?parent=15428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/categories?post=15428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/tags?post=15428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}