{"id":9979,"date":"2010-05-01T00:00:19","date_gmt":"2010-04-30T22:00:19","guid":{"rendered":"http:\/\/test.graswurzel.net\/gwr\/?p=9979"},"modified":"2022-07-26T13:11:41","modified_gmt":"2022-07-26T11:11:41","slug":"wir-brauchen-eine-anti-atom-revolution","status":"publish","type":"post","link":"https:\/\/www.graswurzel.net\/gwr\/2010\/05\/wir-brauchen-eine-anti-atom-revolution\/","title":{"rendered":"&#8222;Wir brauchen eine Anti-Atom-Revolution&#8220;"},"content":{"rendered":"<p>Vladimir Sliwyak, Mitglied der russischen Umweltschutzgruppe                 Ecodefence, begeisterte mit seinem starken Redebeitrag die Menschen                 auf der Anti-Atom-Demo am 24. April am Brennelementezwischenlager                 (BEZ) in Ahaus.<\/p>\n<p>Zuletzt, am 20. Dezember 2009, waren es bei klirrender K\u00e4lte                 nur 350 Leute, die zur bundesweiten Anti-Atom-Demo nach Ahaus                 kamen (vgl. GWR 345).<\/p>\n<p>Diesmal, auch dank Sonnenschein und sommerlichen Temperaturen,                 kamen zwanzigmal so viele DemonstrantInnen in die westf\u00e4lische                 Kleinstadt: 7.000. So viele wie seit der Anti-Castor-Demo 1998                 nicht mehr. Vor dem BEZ setzten sich die AtomkraftgegnerInnen                 symbolisch vor die Haupteinfahrt des Zwischenlagers, um gegen                 die geplanten Atomm\u00fclltransporte zu protestieren. Sie lauschten                 interessanten Redebeitr\u00e4gen, beispielsweise von Kletteraktivistin                 C\u00e9cile Lecomte, GWR-Autor Matthias Eickhoff (SofA), Olga, einer                 russischen Anarchistin aus St. Petersburg und den &#8222;Katholischen                 Frauen Deutschlands&#8220;.<\/p>\n<p>Sie h\u00f6rten Livemusik unter anderem vom Anarchorapper Chaoze One                 und reihten sich geduldig und gut gelaunt in die Warteschlangen                 vor den Volxk\u00fcchen und Infost\u00e4nden ein. <\/p>\n<p>Doch Ahaus war an diesem Tag eine vergleichsweise kleine Demo.<\/p>\n<h3>Aufsehen erregend! <\/h3>\n<p>Bundesweit haben am 24. April 2010, 24 Jahre nach dem Super-GAU                 von Tschernobyl, bis zu 150.000 Menschen f\u00fcr die Stilllegung aller                 Atomanlagen und gegen die von der CDU\/FDP-Regierung geplante Laufzeitverl\u00e4ngerung                 f\u00fcr deutsche Atomkraftwerke demonstriert. <\/p>\n<p>Rund 120.000 DemonstrantInnen bildeten eine 120 Kilometer lange                 Menschenkette zwischen den Atomkraftwerken Brunsb\u00fcttel und Kr\u00fcmmel,                 20.000 umzingelten das Atomkraftwerk Biblis.<\/p>\n<p>&#8222;Wir sind \u00fcberw\u00e4ltigt von diesem Erfolg. Der Protest war gro\u00df,                 er war vielf\u00e4ltig und bunt, er hat Spa\u00df gemacht. Die hoch gesteckten                 Ziele, eine 120 Kilometer lange Menschenkette zu bilden und zugleich                 den Schrottmeiler Biblis zu umzingeln, haben wir gemeinsam erreicht.                 Hunderte haben sich in den vergangenen Monaten f\u00fcr dieses Ereignis                 engagiert und das Ergebnis ist eine klare politische Forderung:                 Atomkraft abschalten!&#8220; <\/p>\n<p>So das Res\u00fcmee des ehemaligen <i>Graswurzelrevolution<\/i>-Redakteurs                 Jochen Stay, der in den letzten Wochen ger\u00f6delt hat, um die Idee                 der Menschenkette in die Tat umzusetzen.<\/p>\n<p>Bei den Demonstrationen am 24. April war un\u00fcbersehbar, dass sich                 die Anti-Atom-Bewegung seit der Berliner Gro\u00dfdemo mit 50.000 Leuten                 am 5. September 2009, nochmals verbreitert hat.<\/p>\n<p>Neben den unz\u00e4hligen &#8222;Atomkraft? Nein danke&#8220;-Fahnen aus dem Hause                 &#8222;aus.gestrahlt&#8220;, waren viele schwarz-rote, attac-, Gr\u00fcne-, Linkspartei-                 und sogar SPD-Fahnen und Luftballons zu sehen. Auch christliche                 und Eine-Welt-Gruppen waren pr\u00e4sent. <\/p>\n<h3>Die Anti-Atom-Bewegung hat sich verj\u00fcngt<\/h3>\n<p>Alle Generationen waren vertreten, aber die vielen Jugendlichen                 d\u00fcrften den Altersdurchschnitt dieser in W\u00fcrde in die Jahre gekommenen                 sozialen Bewegung deutlich gesenkt haben.<\/p>\n<p>Erfreulich ist auch, dass das Interesse an alternativer Bewegungsliteratur                 offensichtlich gr\u00f6\u00dfer <\/p>\n<p>geworden ist. Den <i>Graswurzelrevolution<\/i>-Handverk\u00e4uferInnen                 wurde die Zeitung f\u00f6rmlich aus der Hand gerissen. <\/p>\n<p>Viele nervt es dagegen, wenn gr\u00fcne Politikerinnen wie Claudia                 Roth und Co. die Anti-Atom-Demonstrationen dazu missbrauchen hier                 ihre billige Wahlpropagandashow abzuziehen.<\/p>\n<p>Wohltuend ist da die Kritik an der parteipolitischen Einflussnahme                 der Menschen- und Aktionskette, wie sie einen Tag danach die B\u00fcrgerinitiative                 L\u00fcchow-Danneberg formuliert hat. <\/p>\n<p>Es w\u00e4re v\u00f6llig falsch, den massenhaften Protest dahingehend umzum\u00fcnzen,                 dass die Hunderttausend angesichts der Pl\u00e4ne von Schwarz-Gelb,                 die Laufzeiten der Atomkraftwerke zu verl\u00e4ngern, den rot-gr\u00fcnen                 &#8222;Atomkompromiss&#8220; verteidigen wollten. &#8222;Dieser Vertrag mit den                 Konzernvertretern ist uns ein Dorn im Auge, denn Rot-Gr\u00fcn hat                 seinerzeit den st\u00f6rungsfreien Betrieb der Atomkraftwerke garantiert                 und sich sogar die angebliche &#8218;Eignungsh\u00f6ffigkeit&#8216; von Gorleben                 in den Vertragstext hinein diktieren lassen. Wir bleiben als die                 Sofortisten treibende Kraft in der Atomausstiegsdebatte und lassen                 uns nicht an die Kette legen&#8220;, kommentiert die BI treffend. <\/p>\n<p>Gro\u00dfdemonstrationen bieten auch f\u00fcr Graswurzelrevolution\u00e4rInnen                 die M\u00f6glichkeit mit parteifixierten Leuten ins Gespr\u00e4ch zu kommen.                 Und wie wollen wir die Menschen f\u00fcr eine gewaltfreie, herrschaftslose                 Gesellschaft begeistern, wenn nicht durch direkte Kommunikation?<\/p>\n<p>Bei den Diskussionen mit Parteijugendlichen ist mir bewusst geworden,                 dass es n\u00f6tig ist, immer <\/p>\n<p>wieder auch Erinnerungsarbeit zu leisten. Erinnern m\u00f6chte ich                 in diesem Zusammenhang zum Beispiel daran, dass es in den 1970er                 Jahren Pl\u00e4ne gab, bis zu 200 Atomkraftwerke in Deutschland zu                 bauen. <\/p>\n<p>Dass davon nur ein Bruchteil durchgesetzt werden konnte, ist                 vor allem dem beharrlichen Widerstand der Anti-Atom-Bewegung zu                 verdanken, nicht den Parteien. Das Gleiche gilt f\u00fcr die Wiederaufbereitungsanlage                 (WAA), die die Atommafia zuerst in Gorleben durchsetzen wollte.                 Als der nieders\u00e4chsische CDU-Ministerpr\u00e4sident Ernst Albrecht                 dann einr\u00e4umen musste, dass die WAA im Wendland aufgrund des massiven                 Widerstands der Bev\u00f6lkerung nicht durchsetzbar sei, wollte der                 bayrische CSU-Ministerpr\u00e4sident Franz-Josef Strau\u00df die WAA in                 Wackersdorf bauen lassen, wo aufgrund der absoluten 60 Prozent-CSU-Mehrheit                 kaum Widerstand zu erwarten sei. <\/p>\n<p>Frei nach Herbert Achternbusch: &#8222;60 % der Bayern sind Anarchisten.                 Und die w\u00e4hlen alle CSU.&#8220; <\/p>\n<p>Tats\u00e4chlich leistete nicht zuletzt auch die \u00f6rtliche Bev\u00f6lkerung                 massiven Widerstand, die Bauern kippten immer wieder Jauche in                 die WAA-Bohrl\u00f6cher und der Bauzaun wurde so l\u00f6chrig wie ein Schweizer                 K\u00e4se. Die unter anderem aufgrund des vielf\u00e4ltigen Protests, der                 Sabotage und anderer direkter gewaltfreier Aktionen gestiegenen                 WAA-Baukosten, veranlassten schlie\u00dflich die Atomindustrie dazu,                 ihr gr\u00f6\u00dftes Bauprojekt aufzugeben. <\/p>\n<p>Aus der Tatsache, dass die wichtigsten Atomstaatsprojekte in                 Deutschland in unionsregierten Bundesl\u00e4ndern verhindert werden                 konnten, k\u00f6nnte der Schluss gezogen werden, dass es nicht so wichtig                 ist, wer die Regierung stellt. Wichtig ist der Widerstand, wichtig                 sind die sozialen Bewegungen, die sich gegen den Atomstaat stemmen.               <\/p>\n<h3>Dass die Anti-Atom-Bewegung jetzt einen neuen Fr\u00fchling erlebt,                 ist ein Hoffnungsschimmer <\/h3>\n<p>Und der Sommer steht vor der T\u00fcr: Am 5. Juni 2010 wird der Schwarzbau                 Gorleben umzingelt. <\/p>\n<p>&#8222;30 Jahre nach der R\u00e4umung des legend\u00e4ren H\u00fcttendorfes 1004 werden                 wir den widerst\u00e4ndigen Geist aus der Flasche lassen und den Fokus                 als n\u00e4chstes auf Gorleben und das Atomm\u00fclldilemma richten. Im                 Herbst organisieren wir anl\u00e4sslich des n\u00e4chsten Castortransports                 nach Gorleben eine Abstimmung mit den F\u00fc\u00dfen, Atomkraftwerke geh\u00f6ren                 abgeschaltet, statt des Ausbaus in Gorleben fordern wir den R\u00fcckbau                 der Schachtanlage. Gorleben ist politisch vermurkst und geologisch                 sicher wie die Asse und Morsleben&#8220;, erkl\u00e4rte am 25. April Wolfgang                 Ehmke, ein Sprecher der BI L\u00fcchow-Dannenberg.<\/p>\n<p>Der Winter ist vorbei, und &#8222;wir werden alles geben, dass der                 Traum Wirklichkeit wird&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vladimir Sliwyak, Mitglied der russischen Umweltschutzgruppe Ecodefence, begeisterte mit seinem starken Redebeitrag die Menschen auf der Anti-Atom-Demo am 24. April am Brennelementezwischenlager (BEZ) in Ahaus. Zuletzt, am 20. Dezember 2009, waren es bei klirrender K\u00e4lte nur 350 Leute, die zur bundesweiten Anti-Atom-Demo nach Ahaus kamen (vgl. GWR 345). Diesmal, auch dank Sonnenschein und sommerlichen Temperaturen, &hellip; <a href=\"https:\/\/www.graswurzel.net\/gwr\/2010\/05\/wir-brauchen-eine-anti-atom-revolution\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"slim_seo":{"title":"\"Wir brauchen eine Anti-Atom-Revolution\" - graswurzelrevolution","description":"Vladimir Sliwyak, Mitglied der russischen Umweltschutzgruppe Ecodefence, begeisterte mit seinem starken Redebeitrag die Menschen auf der Anti-Atom-Demo am 24. A"},"footnotes":""},"categories":[565,1039],"tags":[],"class_list":["post-9979","post","type-post","status-publish","format-standard","hentry","category-349-mai-2010","category-quergestellt"],"_links":{"self":[{"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/posts\/9979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/comments?post=9979"}],"version-history":[{"count":0,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/posts\/9979\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/media?parent=9979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/categories?post=9979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.graswurzel.net\/gwr\/wp-json\/wp\/v2\/tags?post=9979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}